{"id":922,"date":"2023-12-26T06:47:32","date_gmt":"2023-12-26T06:47:32","guid":{"rendered":"https:\/\/immediateconnect.club\/?page_id=922"},"modified":"2025-12-11T11:37:29","modified_gmt":"2025-12-11T11:37:29","slug":"politica-sulla-riservatezza","status":"publish","type":"page","link":"https:\/\/immediateconnect.club\/it\/privacy-policy\/","title":{"rendered":"politica sulla riservatezza"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"922\" class=\"elementor elementor-922\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3744526 e-flex e-con-boxed e-con e-parent\" data-id=\"3744526\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8608710 elementor-widget elementor-widget-heading\" data-id=\"8608710\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">politica sulla riservatezza <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a2b1de e-flex e-con-boxed e-con e-parent\" data-id=\"6a2b1de\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f1135d9 elementor-widget elementor-widget-heading\" data-id=\"f1135d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. Introduzione<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f3d42f elementor-widget elementor-widget-text-editor\" data-id=\"2f3d42f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La dichiarazione successiva delinea i dettagli di <a href=\"https:\/\/immediateconnect.club\/it\/\">Immediate Connect&#8217;s<\/a> Informativa sulla privacy, dove \"noi\", \"noi\" o \"nostro\" si riferiscono all'azienda, relativa ai prodotti e servizi (\"Servizi\") nonch\u00e9 al sito web (\"Sito web\"). La tutela della tua privacy e la salvaguardia dell'integrit\u00e0 di tutte le informazioni che fornisci sono per noi fondamentali per l'efficace fornitura dei nostri Servizi e il funzionamento del Sito web.<\/p><p>I nostri Servizi e\/o il Sito Web possono essere collegati ad altri siti e\/o servizi di terze parti. Decliniamo esplicitamente la responsabilit\u00e0 per le pratiche sulla privacy su queste piattaforme esterne e consigliamo di rivedere le loro politiche sulla privacy prima di utilizzarle.<\/p><p>Qualsiasi informazione raccolta o ottenuta da noi in relazione ai nostri Servizi \u00e8 trattata come riservata. Conserviamo in modo sicuro tutte le informazioni, limitando l'accesso al solo personale autorizzato. Sono in atto rigorose misure tecniche, di sicurezza e organizzative per proteggere i dati personali (come definiti di seguito) da trattamenti non autorizzati o illegali, nonch\u00e9 da perdita accidentale, distruzione, danneggiamento, furto o divulgazione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d191424 elementor-widget elementor-widget-heading\" data-id=\"d191424\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informazioni che raccogliamo\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-152511a elementor-widget elementor-widget-text-editor\" data-id=\"152511a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le informazioni personali che ti verr\u00e0 chiesto di fornire e i motivi per cui ti verr\u00e0 chiesto di fornirle ti saranno chiariti nel momento in cui ti chiederemo di fornire le tue informazioni personali. Se ci contatti direttamente, potremmo ricevere ulteriori informazioni su di te, come il tuo nome, indirizzo email, numero di telefono, il contenuto del messaggio e\/o degli allegati che potresti inviarci e qualsiasi altra informazione che potresti scegliere di fornire. Quando registri un Account, potremmo chiederti le tue informazioni di contatto, tra cui nome, nome dell'azienda, indirizzo, indirizzo e-mail e numero di telefono.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ad2650 elementor-widget elementor-widget-heading\" data-id=\"5ad2650\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2. Sito web; Visitatori e Utenti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-548aec4 elementor-widget elementor-widget-heading\" data-id=\"548aec4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.1. Generale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae33ab4 elementor-widget elementor-widget-text-editor\" data-id=\"ae33ab4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le sezioni successive forniscono dettagli riguardanti i gruppi specifici da cui vengono raccolti i Dati Personali. Questi gruppi includono i visitatori del sito Web (\"Visitatori\"), gli utenti (\"Utenti\") e i partner commerciali (ad esempio affiliati, inserzionisti, editori, agenzie pubblicitarie, piattaforme, ecc.) associati ai nostri Servizi, collettivamente denominati \"Partner .\u201d Ai fini della presente Politica, i Dati personali comprendono informazioni quali indirizzo IP, nome e cognome, indirizzo postale e\/o e-mail, numero di telefono, interesse per prodotti e servizi, informazioni sui contatti e dettagli sul tipo di rapporto esistente tra di noi. e Visitatori, Utenti e\/o Partner. I termini \u201cVisitatori\u201d, \u201cUtenti\u201d e \u201cPartner\u201d hanno il significato loro assegnato nel relativo regolamento sulla protezione dei dati e\/o nella legge.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1de463 elementor-widget elementor-widget-heading\" data-id=\"e1de463\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.2. Raccolta e utilizzo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d92ab52 elementor-widget elementor-widget-text-editor\" data-id=\"d92ab52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Accedendo al sito Web, stai indicando il tuo consenso alla raccolta e all'utilizzo dei tuoi dati personali come indicato nel presente documento. Se non sei d'accordo con i termini qui indicati, ti preghiamo di astenerti dal visitare il sito web. In conformit\u00e0 con le leggi applicabili, richiederemo il tuo consenso esplicito per il trattamento dei Dati Personali ottenuti dal Sito o da te forniti volontariamente. \u00c8 importante notare che qualsiasi consenso prestato \u00e8 del tutto volontario. Tuttavia, se neghi il consenso al trattamento dei tuoi dati personali, ci\u00f2 potrebbe influire sulla tua capacit\u00e0 di utilizzare il sito web.<\/p><p>Potremmo raccogliere, registrare e analizzare le informazioni dei visitatori del sito web. Ci\u00f2 potrebbe comportare la registrazione del tuo indirizzo IP e l'utilizzo di cookie (consultare la Politica sui cookie di seguito). Inoltre, potremmo incorporare dati ottenuti attraverso l'attivit\u00e0 di visualizzazione della pagina. Inoltre, tutti i Dati personali che scegli di fornirci o di rendere accessibili a noi attraverso i moduli del sito Web, ad esempio durante l'iscrizione o l'iscrizione ai nostri Servizi o la ricezione di informazioni, potrebbero essere raccolti ed elaborati. Raccogliamo dati relativi alle visite al sito Web, inclusi numeri di visitatori, frequenze di visita, dati di geolocalizzazione, durata delle visite al sito Web, pagine cliccate e punti di ingresso dei visitatori.<\/p><p>Per gli scopi delineati nella presente Informativa, un \u201cVisitatore\u201d si riferisce a qualsiasi individuo che visita il Sito Web e ne rivede i contenuti, mentre un \u201cUtente\u201d indica qualsiasi Visitatore che riceve attivamente Servizi o fornisce dati (ad esempio, attraverso moduli, processi di registrazione , o altri metodi) sul Sito.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c551aff elementor-widget elementor-widget-heading\" data-id=\"c551aff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.3. Finalit\u00e0 del trattamento dei dati personali<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5114289 elementor-widget elementor-widget-text-editor\" data-id=\"5114289\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Possiamo trattare i dati personali per gestire, migliorare, comprendere e personalizzare il nostro sito Web e\/o i nostri servizi. Ad esempio, utilizziamo i seguenti dati personali per utilizzare i tuoi dati integrati con i dati delle nostre operazioni per migliorare l'accuratezza dei nostri Servizi; Comunicare con te in merito ai Servizi; Contattarti in merito ad annunci di servizio, aggiornamenti o offerte; Fornire supporto e assistenza per i Servizi; Soddisfare o rispettare obblighi contrattuali o legali nei confronti dei nostri Partner; Collaborare, cooperare e lavorare in altro modo con i nostri partner, venditori e fornitori di servizi; Condivisione delle informazioni personali con i nostri partner, venditori e fornitori di servizi che potrebbero eseguire servizi per nostro conto (ad esempio, tramite API e\/o altri mezzi elettronici e digitali); Applicare i nostri Termini di utilizzo e\/o le nostre Politiche; Inoltre, potremmo comunicare con te attraverso i mezzi che ci hai fornito per farlo.<\/p><p>Non tratteremo i Dati Personali a meno che non esista una base legale per tale trattamento.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26e1616 elementor-widget elementor-widget-heading\" data-id=\"26e1616\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.4. Condivisione dei dati personali<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc780d7 elementor-widget elementor-widget-text-editor\" data-id=\"cc780d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Potremmo anche divulgare tali informazioni a fornitori di servizi, partner e\/o appaltatori per soddisfare un servizio o una transazione richiesta o per analizzare il comportamento dei visitatori e\/o degli utenti sul sito Web e\/o sui siti Web dei partner.<\/p><p>Per i visitatori e\/o gli utenti con account nella regione dati europea, tutto il trattamento dei dati personali rispetta i diritti e le normative sulla privacy, come delineato nel Regolamento generale sulla protezione dei dati (GDPR) e\/o nelle leggi e nei regolamenti pertinenti sulla protezione dei dati.<\/p><p>I dati personali che ti riguardano potrebbero essere trasferiti a un paese terzo (ovvero, giurisdizioni al di fuori dello Spazio Economico Europeo (\u201cSEE\u201d)) o a organizzazioni internazionali. In tali casi, faremo ogni ragionevole sforzo per salvaguardare e garantire la protezione dei tuoi dati personali, fornendo diritti applicabili agli interessati e rimedi legali efficaci.<\/p><p>Tali garanzie e protezioni saranno applicabili alle seguenti condizioni:<\/p><p>(a) Il trasferimento avviene verso un paese terzo o un'organizzazione internazionale che la Commissione UE ha ritenuto fornire un livello adeguato di protezione per i dati personali trasferiti, ai sensi dell'articolo 45, paragrafo 3, del GDPR.<\/p><p>(b) Il trasferimento \u00e8 effettuato mediante uno strumento giuridicamente vincolante ed esecutivo tra autorit\u00e0 o organismi pubblici, ai sensi dell'articolo 46, paragrafo 2, lettera a), del GDPR.<\/p><p>(c) Il trasferimento \u00e8 conforme alle clausole tipo di protezione dei dati adottate dalla Commissione UE, ai sensi dell'articolo 46, paragrafo 2, lettera c), del GDPR.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97d310f elementor-widget elementor-widget-heading\" data-id=\"97d310f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3. Partner<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0dd7bf elementor-widget elementor-widget-heading\" data-id=\"a0dd7bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3.1. Generale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b907f51 elementor-widget elementor-widget-text-editor\" data-id=\"b907f51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per facilitare i nostri Servizi e collaborare con i Partner, potremmo raccogliere o acquisire da loro tipi di dati specifici. I partner possono caricare, trasmettere, importare, pubblicare o elaborare dati anonimizzati riguardanti i propri utenti, visitatori e\/o clienti (\"Dati\"). Durante l'utilizzo dei nostri Servizi, un Partner pu\u00f2 fornirci informazioni su se stesso e\/o sui suoi utenti, visitatori e\/o clienti tramite API e\/o altri mezzi elettronici e digitali. Al Partner \u00e8 vietato utilizzare i Servizi per raccogliere o archiviare informazioni di identificazione personale (informazioni che possono identificare un individuo) e trasmetterci tali dati. Utilizziamo queste informazioni per identificare il Partner e\/o i suoi utenti, visitatori e\/o clienti, agevolando la fornitura dei nostri Servizi, il supporto, la posta, le attivit\u00e0 di vendita e marketing, la fatturazione (se richiesta o applicabile) e il rispetto dei contratti obblighi con il rispettivo Partner. Inoltre, accederemo alle informazioni relative agli utenti, ai visitatori e\/o ai clienti del Partner solo dopo che sono state pseudonimizzate dal Partner, a meno che non sia stato espressamente consentito dagli utenti, visitatori e\/o clienti, o imposto dalla legge e\/o da disposizioni legali. autorit\u00e0.<\/p><p>Il Partner riconosce: (i) il Servizio non funziona come un servizio di archiviazione o archiviazione di file e non siamo obbligati a archiviare o eseguire il backup dei dati che i Partner caricano, importano o pubblicano per noi o generano durante l'utilizzo del Servizio; (ii) il Partner \u00e8 l'unico responsabile del backup dei Dati; e (iii) l'accesso a qualsiasi dato che sia stato cancellato \u00e8 a nostra esclusiva discrezione o come richiesto dalla legge e\/o dalle autorit\u00e0 legali.<\/p><p>Il Partner comprende e riconosce che Internet e le sue comunicazioni possono non essere sicure, creando opportunit\u00e0 di accesso non autorizzato a sistemi informatici, reti e dati archiviati. Le informazioni e i dati trasmessi su Internet (inclusi i Dati) o archiviati su qualsiasi apparecchiatura che trasmette informazioni su Internet potrebbero non rimanere riservati. Non forniamo alcuna dichiarazione o garanzia in merito alla privacy, alla sicurezza, all'autenticit\u00e0, alla non corruzione o alla distruzione di tali informazioni. Il Partner si assume il rischio di utilizzare qualsiasi informazione trasmessa o ottenuta su Internet e decliniamo ogni responsabilit\u00e0 per eventuali conseguenze negative o perdite derivanti dall'uso di Internet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-793fb8c elementor-widget elementor-widget-heading\" data-id=\"793fb8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3.2. Trattamento dei dati personali<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f843927 elementor-widget elementor-widget-text-editor\" data-id=\"f843927\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dipendiamo dal consenso del Partner per gestire i Dati personali e\/o dalle garanzie del Partner di aver ottenuto il consenso necessario dai propri utenti, visitatori e\/o clienti. In alternativa, potremmo trattare i Dati Personali quando \u00e8 essenziale per adempiere a un obbligo contrattuale con il Partner o quando richiesto dalla legge.<\/p><p>Inoltre, possiamo trattare i Dati personali quando ci\u00f2 \u00e8 nell\u2019interesse legittimo nostro o dei nostri Partner, a condizione che tali interessi non prevalgano sui diritti di protezione dei dati dell\u2019individuo, che possono variare in base alla loro giurisdizione.<\/p><p>Il Partner riconosce e accetta che i Dati fornitici possano includere informazioni di identificazione personale o dati personali, come definito dalle leggi pertinenti che regolano l'utilizzo dei dati riguardanti persone fisiche identificate o identificabili nell'UE e\/o nello stato della California negli Stati Uniti. Ci\u00f2 include, tra le altre, leggi come il Data Protection Act dell\u2019UE del 1998, il Regolamento generale sulla protezione dei dati dell\u2019UE (GDPR) e il California Consumer Protection Act in vigore dal 1\u00b0 gennaio 2020.<\/p><p>Il Partner ci concede un diritto non esclusivo e una licenza per elaborare i dati allo scopo di fornire i servizi. Possiamo anche redigere, rendere anonimi e\/o aggregare i Dati con contenuti e dati di altri Partner o raccolti da noi, come indicato nella presente Informativa, per scopi quali lo sviluppo di prodotti e servizi, la commercializzazione e iniziative di miglioramento della qualit\u00e0. Tutte le aggregazioni di dati saranno di nostra sola ed esclusiva propriet\u00e0.<\/p><p>Il Partner dichiara di aver ottenuto legalmente informazioni di identificazione personale o dati personali in conformit\u00e0 con le leggi e i regolamenti applicabili sulla protezione dei dati. Hanno adeguatamente comunicato a utenti, visitatori e\/o clienti come le informazioni di identificazione personale o i dati personali verranno utilizzati, elaborati, archiviati e\/o condivisi, come richiesto dalle leggi pertinenti. Il Partner \u00e8 responsabile di onorare le richieste di utenti, visitatori e\/o clienti relative alla raccolta, all'uso e all'archiviazione di informazioni di identificazione personale o dati personali, come previsto dalle leggi pertinenti.<\/p><p>Il Partner inoltre dichiara e garantisce di possedere o di aver acquisito il diritto a tutti i diritti di propriet\u00e0 intellettuale sui Dati e di avere il diritto di fornirci la licenza qui concessa. Inoltre, affermano che i Dati non violano n\u00e9 brevetti, diritti d'autore, marchi o altri diritti di propriet\u00e0 intellettuale, propriet\u00e0 o privacy di terze parti. Il Partner rimane l'unico responsabile dei Dati, sollevandoci da ogni e qualsiasi responsabilit\u00e0 derivante da tali attivit\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e40917 elementor-widget elementor-widget-heading\" data-id=\"3e40917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3.3. Controllore\/Processore<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b46d36e elementor-widget elementor-widget-text-editor\" data-id=\"b46d36e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Possiamo trattare i dati personali sia come responsabile del trattamento che come responsabile del trattamento, come definito nel GDPR e\/o nelle leggi e nei regolamenti sulla protezione dei dati:<\/p><p>Quando si tratta di dati forniti da Visitatori e\/o Utenti, agiamo come Titolari del trattamento in conformit\u00e0 con il GDPR e\/o le leggi e i regolamenti pertinenti sulla protezione dei dati.<\/p><p>Per i dati relativi ai Partner e\/o appartenenti ai Partner e ai loro utenti, visitatori e\/o clienti, forniti dal Partner a noi, fungeremo da Responsabile del trattamento in conformit\u00e0 con il GDPR e\/o le Leggi e i regolamenti sulla protezione dei dati.<\/p><p>Tutti i dati da noi raccolti vengono archiviati in modo sicuro in strutture di hosting che aderiscono ai pi\u00f9 elevati standard di sicurezza. I nostri accordi con i fornitori di hosting garantiscono il rispetto delle pi\u00f9 severe norme di sicurezza.<\/p><p>Abbiamo implementato ragionevoli misure di salvaguardia fisiche, tecniche e organizzative per proteggere da distruzione, perdita, alterazione, divulgazione, accesso, utilizzo o elaborazione accidentali, non autorizzati o illegali dei dati del Partner e\/o del Partner e dei suoi utenti, visitatori e \/o dati dei clienti e\/o dati personali in nostro possesso. In caso di accesso o utilizzo non autorizzato, informeremo tempestivamente il Partner.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48a6c18 elementor-widget elementor-widget-heading\" data-id=\"48a6c18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3.4. Protezione dei dati di terze parti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b66a16 elementor-widget elementor-widget-text-editor\" data-id=\"4b66a16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nei casi in cui l'utilizzo dei Servizi da parte del Partner comporta il trattamento dei dati personali appartenenti ai suoi utenti, visitatori e\/o clienti, come componente del suo impegno con una piattaforma di terze parti ai sensi del GDPR e\/o delle leggi sulla protezione dei dati e Regolamento, detta piattaforma assumer\u00e0 il ruolo di Titolare. Il Partner, a sua volta, funger\u00e0 da Responsabile del trattamento e si impegna a:<\/p><p>(a) Aderire e agire esclusivamente in base alle istruzioni ricevute dalla piattaforma terza in merito al trattamento di detti Dati Personali;<\/p><p>(b) die Verarbeitung dieser personenbezogenen Daten ausschlie\u00dflich auf die mit der Bereitstellung der Dienste verbundenen Zwecke beschr\u00e4nken;<\/p><p>(c) Implementare misure tecniche e organizzative adeguate per prevenire trattamenti non autorizzati o illegali, nonch\u00e9 proteggere contro la perdita, la distruzione o il danneggiamento dei Dati Personali;<\/p><p>(d) Garantire l'integrit\u00e0 di tutto il personale che accede o \u00e8 destinato ad accedere ai Dati personali;<\/p><p>(e) Evitare qualsiasi azione o svista che potrebbe comportare una violazione delle leggi sulla protezione dei dati per la piattaforma di terze parti e\/o per noi;<\/p><p>(f) Notificare tempestivamente alla piattaforma di terze parti e\/o a noi qualsiasi violazione sospetta o confermata della protezione dei dati o trattamento non autorizzato e illegale, perdita, distruzione o danno ai Dati personali;<\/p><p>(g) Ottenere il consenso esplicito scritto dalla piattaforma prima di subappaltare qualsiasi obbligo di trattamento relativo ai Dati personali a terzi;<\/p><p>(h) Astenersi dal trattare i Dati Personali al di fuori dello Spazio Economico Europeo senza ottenere il previo consenso scritto della piattaforma di terze parti e soddisfare tutti i requisiti previsti per tale trattamento extraterritoriale;<\/p><p>(i) In caso di comunicazioni di marketing elettronico, assicurarsi che il destinatario abbia dato il consenso, fornire un'opzione di annullamento dell'iscrizione con ogni comunicazione e rispettare qualsiasi richiesta di annullamento dell'iscrizione, quando si agisce per conto del Partner o della piattaforma di terze parti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2353784 elementor-widget elementor-widget-heading\" data-id=\"2353784\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4. Sicurezza<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69b3bc0 elementor-widget elementor-widget-text-editor\" data-id=\"69b3bc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Adottiamo ragionevoli garanzie amministrative, organizzative e tecniche e misure di sicurezza per salvaguardare i dati personali da accessi non autorizzati, divulgazione, distruzione o alterazione, nonch\u00e9 perdita accidentale, uso improprio o danno.<\/p><p>Nelle situazioni in cui la divulgazione dei dati a terzi \u00e8 ritenuta necessaria e autorizzata, ci assicuriamo che tali terzi si impegnino a mantenere un livello di protezione dei dati equivalente a quello da noi fornito. Questo impegno comporta obblighi contrattuali volti a garantire che i dati siano trattati esclusivamente in conformit\u00e0 con le disposizioni delineate nella presente Policy, in linea con le finalit\u00e0 concordate dal Partner, e gestiti con la necessaria riservatezza e sicurezza.<\/p><p>Se un Visitatore, Utente e\/o Partner ha motivo di sospettare che le sue interazioni con noi non siano pi\u00f9 sicure, ne incoraggiamo la tempestiva notifica.<\/p><p>Tieni presente che, sebbene adottiamo tutte le misure ragionevoli per prevenire violazioni della sicurezza, non possiamo garantire che i nostri protocolli di sicurezza renderanno le informazioni immuni dall'accesso illegale da parte di \"hacker\" di terze parti robusto, potrebbe non essere completamente a prova di violazione. Pertanto, i Visitatori, gli Utenti e\/o i Partner si assumono il rischio associato a tali violazioni, riconoscendo che potrebbero verificarsi nonostante i nostri migliori sforzi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b7ed4c elementor-widget elementor-widget-heading\" data-id=\"2b7ed4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5. Biscotti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b821cf elementor-widget elementor-widget-text-editor\" data-id=\"3b821cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Consulta la nostra Politica sui cookie per ulteriori informazioni sul tipo di cookie e sulle tecnologie di tracciamento che utilizziamo sul sito web, sul perch\u00e9 e su come accettarli o rifiutarli.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81e7332 elementor-widget elementor-widget-heading\" data-id=\"81e7332\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">6. Collegamenti ad altri siti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-baae820 elementor-widget elementor-widget-text-editor\" data-id=\"baae820\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durante la navigazione nel sito web, si tenga presente che i Visitatori e\/o gli Utenti potrebbero incontrare collegamenti a siti esterni al di fuori del nostro controllo o influenza. Decliniamo ogni responsabilit\u00e0 per il contenuto o le politiche sulla privacy di questi siti esterni.<\/p><p>Quando accedi a siti Web e\/o servizi di terzi (compresi quelli dei nostri Partner), ti consigliamo di rivedere attentamente le loro politiche sulla privacy prima di utilizzare tali siti Web e\/o servizi e prima di divulgare qualsiasi Dato Personale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a475953 elementor-widget elementor-widget-heading\" data-id=\"a475953\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">7. Conservazione e Cancellazione<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5777d5 elementor-widget elementor-widget-text-editor\" data-id=\"b5777d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ci impegniamo a conservare i dati (compresi i dati personali) solo per il periodo necessario a soddisfare gli scopi per i quali sono stati raccolti o come richiesto dalle leggi o dai regolamenti applicabili. Per i dati dei Visitatori e\/o Utenti, chi ha un account attivo si assume la responsabilit\u00e0 di cancellare i dati quando necessario. Alla cessazione o scadenza dell'account di un Visitatore e\/o Utente o alla cessazione del nostro rapporto contrattuale con un Partner, tutti i Dati personali associati raccolti attraverso il Sito Web e\/o i Servizi verranno eliminati, in conformit\u00e0 con la legge applicabile e i nostri requisiti interni e interessi legittimi.<\/p><p>Nei casi in cui la base giuridica per il trattamento dei Dati Personali si basa sul consenso, hai il diritto di revocare il tuo consenso in qualsiasi momento avvisandoci all'indirizzo email fornito di seguito. Se il consenso viene revocato, potremmo non essere in grado di fornire alcuni o tutti i Servizi richiesti e non avrai alcun diritto al riguardo.<\/p><p>Quando il trattamento dei dati personali che ti riguardano \u00e8 ritenuto necessario per gli interessi legittimi perseguiti da noi o da terzi (compresi i nostri partner), tale trattamento \u00e8 subordinato a quegli interessi non in conflitto con i tuoi interessi o diritti e libert\u00e0 fondamentali che richiedono la protezione di i tuoi dati personali. Puoi contattarci in qualsiasi momento tramite l'indirizzo e-mail riportato di seguito per ottenere informazioni sulla revisione da noi condotta per determinare se il trattamento dei tuoi dati personali \u00e8 necessario per gli interessi legittimi perseguiti da noi o da terzi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97ec280 elementor-widget elementor-widget-heading\" data-id=\"97ec280\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">8. Right of Access<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85808db elementor-widget elementor-widget-text-editor\" data-id=\"85808db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hai il diritto di ricevere conferma se \u00e8 o meno in corso un trattamento dei tuoi Dati Personali. In tal caso, hai il diritto di accedere ai Dati personali e ottenere dettagli tra cui: (1) le finalit\u00e0 del trattamento; (2) le categorie di Dati Personali interessate; (3) destinatari o categorie di destinatari, in particolare quelli al di fuori del SEE o delle organizzazioni internazionali; (4) la durata di conservazione prevista o i criteri utilizzati se una durata specifica non \u00e8 fattibile; (5) il tuo diritto di richiedere la limitazione del trattamento o di opporti allo stesso; (6) il diritto di proporre reclamo a un'autorit\u00e0 di controllo; (7) informazioni sulla fonte dei Dati Personali se non raccolti presso di te (in conformit\u00e0 agli obblighi contrattuali); (8) l'esistenza della profilazione; e (9) dettagli sulle garanzie per i dati personali trasferiti al di fuori del SEE o a organizzazioni internazionali.<\/p><p>Ti forniremo una copia dei Dati personali oggetto del trattamento e potremmo addebitare un costo ragionevole per copie aggiuntive. Se la richiesta viene effettuata elettronicamente, e salvo diversa indicazione da parte dell'utente, le informazioni verranno fornite in un formato elettronico comunemente utilizzato.<\/p><p>Tuttavia, il diritto di ottenere una copia dei Dati Personali non violer\u00e0 i diritti e le libert\u00e0 altrui. Pertanto, se l'adempimento della tua richiesta mette a repentaglio i diritti e le libert\u00e0 di altri o i nostri obblighi contrattuali nei confronti di terzi, potremmo rifiutare la tua richiesta o fornire informazioni limitate.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78d41ed elementor-widget elementor-widget-heading\" data-id=\"78d41ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">8.2. Diritto di rettifica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68bdb12 elementor-widget elementor-widget-text-editor\" data-id=\"68bdb12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hai il diritto di richiederci la correzione di eventuali inesattezze nei tuoi dati personali. Considerate le finalit\u00e0 del trattamento, hai anche il diritto di garantire che eventuali Dati Personali incompleti che ti riguardano siano integrati, il che potrebbe comportare la fornitura di informazioni aggiuntive.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2a5cb6 elementor-widget elementor-widget-heading\" data-id=\"a2a5cb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">8.3. Diritto alla cancellazione<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3c6ccf elementor-widget elementor-widget-text-editor\" data-id=\"b3c6ccf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hai il diritto di richiedere la cancellazione dei Dati personali che ti riguardano nelle seguenti circostanze: (a) quando i Dati personali non sono pi\u00f9 necessari per lo scopo di raccolta o trattamento originariamente previsto; (b) se revochi il tuo consenso, non esistono le basi per il trattamento e non esistono basi giuridiche alternative per il trattamento; (c) quando ti opponi, per motivi specifici alla tua situazione, al trattamento dei Dati personali basato sugli interessi legittimi nostri o di terzi (compresi i nostri Partner), senza che prevalgano motivi legittimi per il trattamento; (d) se ti opponi al trattamento dei Dati Personali per finalit\u00e0 di marketing diretto; (e) quando i Dati Personali sono stati trattati illecitamente; (f) quando la cancellazione \u00e8 necessaria per adempiere a un obbligo legale ai sensi della legge applicabile.<\/p><p>Tuttavia, tale diritto non \u00e8 applicabile qualora il trattamento sia necessario: (a) per adempiere a un obbligo legale imposto dalla legge applicabile; o (b) per accertare, esercitare o difendere un diritto in sede giudiziaria.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5997fe elementor-widget elementor-widget-heading\" data-id=\"d5997fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">8.4. Diritto di limitazione del trattamento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc98f4f elementor-widget elementor-widget-text-editor\" data-id=\"bc98f4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hai il diritto di richiedere la limitazione del trattamento dei tuoi Dati personali nelle seguenti circostanze: (a) se contesti l'accuratezza dei Dati personali, concedendoci il tempo di verificarne l'accuratezza; (b) quando il trattamento \u00e8 illecito e ti opponi alla cancellazione, richiedendone invece la limitazione dell'utilizzo; (c) se non abbiamo pi\u00f9 bisogno dei Dati personali per il trattamento ma tu ne hai bisogno per accertare, esercitare o difendere un diritto in sede giudiziaria; (d) quando il trattamento \u00e8 necessario per interessi legittimi, a meno che non possiamo dimostrare motivi legittimi convincenti che prevalgono sui tuoi interessi, diritti e libert\u00e0, o per l'accertamento, l'esercizio o la difesa di rivendicazioni legali; (e) quando i Dati Personali sono trattati per finalit\u00e0 di marketing diretto, compresa la profilazione connessa a tale marketing diretto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-422d285 elementor-widget elementor-widget-heading\" data-id=\"422d285\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">8.5. Diritto alla portabilit\u00e0 dei dati<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45ca117 elementor-widget elementor-widget-text-editor\" data-id=\"45ca117\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hai il diritto di ricevere i tuoi dati personali, da te forniti a noi, in un formato strutturato, di uso comune e leggibile da una macchina. Hai anche il diritto di trasmettere questi dati a un altro titolare del trattamento, a condizione che il trattamento si basi sul tuo consenso o su un accordo contrattuale e che il trattamento sia automatizzato.<\/p><p>Quando eserciti il \u200b\u200btuo diritto alla portabilit\u00e0 dei dati, puoi richiedere la trasmissione diretta dei tuoi dati personali da noi a un'altra entit\u00e0, se tecnicamente fattibile. Questo diritto non compromette i tuoi o i nostri diritti previsti dal diritto alla cancellazione e non pregiudica i diritti e le libert\u00e0 degli altri.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81f3ad0 elementor-widget elementor-widget-heading\" data-id=\"81f3ad0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">8.6. Diritto di opposizione<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53bbdf2 elementor-widget elementor-widget-text-editor\" data-id=\"53bbdf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Puoi opporti, in qualsiasi momento, in base alla tua situazione specifica, al trattamento dei tuoi Dati Personali fondato sugli interessi legittimi nostri o di terzi (compresi i nostri Partner), e ci\u00f2 include la profilazione basata su tali interessi. In tali casi, cesseremo di trattare i tuoi dati personali a meno che non possiamo dimostrare validi motivi legittimi che prevalgono sui tuoi interessi, diritti e libert\u00e0, o per rivendicazioni legali.<\/p><p>Inoltre, potrai opporti, in qualsiasi momento, al trattamento dei tuoi Dati Personali per finalit\u00e0 di marketing diretto, compresa la connessa profilazione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8305b2a elementor-widget elementor-widget-heading\" data-id=\"8305b2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">8.7. Diritto di revocare il consenso<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-242b27e elementor-widget elementor-widget-text-editor\" data-id=\"242b27e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hai il diritto di revocare il tuo consenso al trattamento dei Dati Personali che ti riguardano in qualsiasi momento, senza pregiudicare la liceit\u00e0 del trattamento basata sul tuo consenso prima della revoca. Tieni presente che la revoca del consenso potrebbe influire sulla nostra capacit\u00e0 di fornire alcuni dei nostri servizi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd575cf elementor-widget elementor-widget-heading\" data-id=\"dd575cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">9. Materiale pubblicitario e di marketing<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70b7b11 elementor-widget elementor-widget-text-editor\" data-id=\"70b7b11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Accettando ci\u00f2, acconsenti all'utilizzo dei tuoi dati, comprese le informazioni personali e i dettagli di contatto allo scopo di inviarti materiale pubblicitario e di marketing relativo alle nostre attivit\u00e0, prodotti e\/o servizi attuali e\/o futuri. Hai la possibilit\u00e0 di revocare il tuo consenso inviando una comunicazione scritta all'indirizzo email fornito.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08cc234 elementor-widget elementor-widget-heading\" data-id=\"08cc234\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">10. Accettazione della presente Politica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9ad5d4 elementor-widget elementor-widget-text-editor\" data-id=\"d9ad5d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Partiamo dal presupposto che tutti i visitatori, utenti e partner abbiano attentamente esaminato e accettato i contenuti di questa politica. Se qualcuno non \u00e8 d'accordo con questa politica, dovrebbe astenersi dall'utilizzare il sito web e\/o i servizi. Ci riserviamo il diritto di modificare questa politica se necessario. I visitatori, gli utenti e i partner sono incoraggiati a controllare regolarmente questa pagina per eventuali aggiornamenti. Riconosci e accetti che \u00e8 tua responsabilit\u00e0 rivedere periodicamente questa politica e rimanere informato su eventuali modifiche. L'uso continuato del sito web e\/o dei servizi a seguito delle modifiche alle presenti condizioni implica l'accettazione della politica rivista. Salvo diversa indicazione, tutte le modifiche entreranno in vigore a partire dalla pubblicazione della policy aggiornata.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-122c358 elementor-widget elementor-widget-heading\" data-id=\"122c358\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">11. Il nostro obbligo legale di divulgare i dati personali<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22349bd elementor-widget elementor-widget-text-editor\" data-id=\"22349bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Divulgheremo i dati personali di un visitatore, utente o partner senza previa autorizzazione solo quando vi \u00e8 motivo di ritenere che tale divulgazione sia necessaria per stabilire l'identit\u00e0, contattare o avviare procedimenti legali contro una o pi\u00f9 persone sospettate di violare i nostri diritti o i diritti di altri che potrebbero essere danneggiati dalle attivit\u00e0 del visitatore, utente o partner, sia intenzionali che involontarie. Siamo autorizzati a divulgare i dati personali quando esiste un obbligo legale in tal senso.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-282db5f elementor-widget elementor-widget-heading\" data-id=\"282db5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">11. Your Rights in respect of the Personal Data about You<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5fe02a elementor-widget elementor-widget-text-editor\" data-id=\"d5fe02a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In relazione ai tuoi Dati Personali ti spettano i seguenti diritti. L'esercizio di tali diritti avverr\u00e0 tramite l'invio di una e-mail con la richiesta di esercizio del diritto all'indirizzo e-mail sotto indicato <a href=\"mailto:support@immediateconnect.club\">support@immediateconnect.club<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Privacy Policy 1. Introduction The subsequent statement outlines the details of Immediate Connect&#8217;s privacy policy, where &#8220;us,&#8221; &#8220;we,&#8221; or &#8220;our&#8221; refer to the company, concerning the products and services (&#8220;Services&#8221;) as well as the website (&#8220;Website&#8221;). Upholding your privacy and safeguarding the integrity of any information you provide are paramount to us for the effective [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-922","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/immediateconnect.club\/it\/wp-json\/wp\/v2\/pages\/922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immediateconnect.club\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/immediateconnect.club\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/immediateconnect.club\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/immediateconnect.club\/it\/wp-json\/wp\/v2\/comments?post=922"}],"version-history":[{"count":40,"href":"https:\/\/immediateconnect.club\/it\/wp-json\/wp\/v2\/pages\/922\/revisions"}],"predecessor-version":[{"id":2187,"href":"https:\/\/immediateconnect.club\/it\/wp-json\/wp\/v2\/pages\/922\/revisions\/2187"}],"wp:attachment":[{"href":"https:\/\/immediateconnect.club\/it\/wp-json\/wp\/v2\/media?parent=922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}